{"id":64834,"date":"2023-11-08T16:23:02","date_gmt":"2023-11-08T15:23:02","guid":{"rendered":"https:\/\/www.dimomaint.com\/latam\/?page_id=64834"},"modified":"2025-10-14T08:55:56","modified_gmt":"2025-10-14T07:55:56","slug":"transporte-logistica","status":"publish","type":"page","link":"https:\/\/www.dimomaint.com\/latam\/industria\/transporte-logistica\/","title":{"rendered":"Soluci\u00f3n CMMS para transporte y log\u00edstica"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"64834\" class=\"elementor elementor-64834\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0bf84d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0bf84d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a158168\" data-id=\"a158168\" data-element_type=\"column\" data-e-type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4933485 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4933485\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f484b2d\" data-id=\"f484b2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d55369b elementor-widget elementor-widget-heading\" data-id=\"d55369b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Soluci\u00f3n CMMS para transporte y log\u00edstica<\/h1>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97400d3 elementor-widget elementor-widget-text-editor\" data-id=\"97400d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Para las empresas de transporte y log\u00edstica, el mantenimiento de una flota de veh\u00edculos e infraestructura es vital para la satisfacci\u00f3n de los clientes, la huella de carbono y la rentabilidad \u00f3ptima.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18f984a elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"18f984a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/latam\/prueba-gratuita\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Prueba gratis de 30 d\u00edas<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-156e0de\" data-id=\"156e0de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc7d6d7 elementor-widget elementor-widget-image\" data-id=\"cc7d6d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"540\" height=\"403\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/solucion-cmms-para-transporte-y-logistica.png\" class=\"attachment-full size-full wp-image-67739\" alt=\"SOLUCIO\u0301N CMMS PARA TRANSPORTE Y LOGI\u0301STICA\" srcset=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/solucion-cmms-para-transporte-y-logistica.png 540w, https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/solucion-cmms-para-transporte-y-logistica-360x269.png 360w\" sizes=\"(max-width: 540px) 100vw, 540px\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fffca33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fffca33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f94a359\" data-id=\"f94a359\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-578cce5 uael-dual-heading-align-center elementor-widget elementor-widget-uael-dual-color-heading\" data-id=\"578cce5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-module-content uael-dual-color-heading uael-heading-stack-none\">\n\t\t\t<h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-before-heading\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-first-text\" data-elementor-setting-key=\"before_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">CMMS en el transporte y la log\u00edstica:<\/span><\/span><span class=\"uael-adv-heading-stack\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-highlight-text\" data-elementor-setting-key=\"second_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">una necesidad para el departamento de mantenimiento<\/span><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t<\/div>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a3ad8c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3ad8c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-756403f\" data-id=\"756403f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cb559f elementor-widget elementor-widget-image\" data-id=\"9cb559f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img decoding=\"async\" width=\"950\" height=\"608\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/transporte-y-logistica-para-el-cmms-una-necesidad-para-el-area-de-mantenimiento.svg\" class=\"attachment-full size-full wp-image-80246\" alt=\"Transporte y log\u00edstica para el CMMS una necesidad para el \u00e1rea de mantenimiento.\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20a260c\" data-id=\"20a260c\" data-element_type=\"column\" data-e-type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-857ee9c elementor-widget elementor-widget-text-editor\" data-id=\"857ee9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Gestionar el <strong>mantenimiento de una flota de veh\u00edculos, activos fijos e infraestructuras<\/strong> no es una tarea f\u00e1cil.<\/p>\n<p>Para responder a las prioridades de los actores del sector del transporte y la log\u00edstica, se deben ofrecer las <strong>mejores condiciones de funcionamiento<\/strong> con los medios con los que se dispone, <strong>garantizar la seguridad<\/strong> y la <strong>satisfacci\u00f3n de los usuarios<\/strong>, asegurar la <strong>disponibilidad de los activos<\/strong> y el <strong>cumplimiento de la normativa legal<\/strong>, y <strong>optimizar los costos<\/strong>\u2026<\/p>\n<p>Tus t\u00e9cnicos a menudo tienen que recorrer largas distancias para intervenir. Por lo tanto, <strong>cualquier herramienta que les ahorre tiempo tendr\u00e1 un impacto sustancial.<\/strong><\/p>\n<p>Adem\u00e1s, te gustar\u00eda gestionar los informes de los conductores de forma m\u00e1s eficiente y tener una mejor visibilidad del kilometraje y el consumo de sus autobuses, por ejemplo.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-652c766 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"652c766\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-839f4d4\" data-id=\"839f4d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f674e9 elementor-widget elementor-widget-heading\" data-id=\"4f674e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Elegir un CMMS es la mejor manera de ayudarte<\/h3>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-427b624 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"427b624\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a3f91c8\" data-id=\"a3f91c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0103758 elementor-widget elementor-widget-image\" data-id=\"0103758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img decoding=\"async\" width=\"92\" height=\"96\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/gestionar.svg\" class=\"attachment-full size-full wp-image-67747\" alt=\"GESTIONAR\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d17f92 cancelnotlastchild elementor-widget elementor-widget-heading\" data-id=\"5d17f92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">GESTIONAR <\/p>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-189ef3f no-margin elementor-widget elementor-widget-text-editor\" data-id=\"189ef3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>todas las actividades de mantenimiento internas y externas.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-71ee836\" data-id=\"71ee836\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f46ef0d elementor-widget elementor-widget-image\" data-id=\"f46ef0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"96\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/analizar.svg\" class=\"attachment-full size-full wp-image-67748\" alt=\"ANALIZAR\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81ca2d6 cancelnotlastchild elementor-widget elementor-widget-heading\" data-id=\"81ca2d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">ANALIZAR<\/p>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e24902 no-margin elementor-widget elementor-widget-text-editor\" data-id=\"9e24902\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>la actividad de tu flota, equipos e infraestructuras.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e1b41c5\" data-id=\"e1b41c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0d4abc elementor-widget elementor-widget-image\" data-id=\"d0d4abc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"96\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/garantizar.svg\" class=\"attachment-full size-full wp-image-67749\" alt=\"GARANTIZAR\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5372f5 cancelnotlastchild elementor-widget elementor-widget-heading\" data-id=\"e5372f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">GARANTIZAR<\/p>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1935109 no-margin elementor-widget elementor-widget-text-editor\" data-id=\"1935109\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>el seguimiento y el cumplimiento de la normativa.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-79aeb51\" data-id=\"79aeb51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-534d9df elementor-widget elementor-widget-image\" data-id=\"534d9df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"96\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/controlar.svg\" class=\"attachment-full size-full wp-image-67750\" alt=\"CONTROLAR\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da3a787 cancelnotlastchild elementor-widget elementor-widget-heading\" data-id=\"da3a787\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">CONTROLAR<\/p>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbdb6e8 no-margin elementor-widget elementor-widget-text-editor\" data-id=\"dbdb6e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>y optimizar los costos.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-097f81f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"097f81f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba749c9\" data-id=\"ba749c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a652587 uael-dual-heading-align-center elementor-widget elementor-widget-uael-dual-color-heading\" data-id=\"a652587\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-module-content uael-dual-color-heading uael-heading-stack-none\">\n\t\t\t<h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-before-heading\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-first-text\" data-elementor-setting-key=\"before_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">Haz que la gesti\u00f3n del mantenimiento de tu flota de veh\u00edculos y equipos sea<\/span><\/span><span class=\"uael-adv-heading-stack\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-highlight-text\" data-elementor-setting-key=\"second_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">m\u00e1s sencilla y fiable<\/span><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t<\/div>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3a6ecf7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a6ecf7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c80c95c\" data-id=\"c80c95c\" data-element_type=\"column\" data-e-type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cffe7a0 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"cffe7a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"548\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/garantiza-y-controla-la-gestion-del-mantenimiento-de-tu-flota-de-vehiculos-y-equipos.svg\" class=\"attachment-full size-full wp-image-80245\" alt=\"Garantiza y controla la gesti\u00f3n del mantenimiento de tu flota de veh\u00edculos y equipos.\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0f2959 elementor-widget elementor-widget-text-editor\" data-id=\"e0f2959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>El CMMS DimoMaint es una soluci\u00f3n ergon\u00f3mica y sencilla para el seguimiento de la actividad de mantenimiento realizada por proveedores internos y externos en empresas del sector del transporte y la log\u00edstica. Las empresas de transporte y log\u00edstica necesitan activos operativos e informes f\u00e1ciles de entender.<\/p>\n<p>Para los equipos t\u00e9cnicos, <strong>acceder al historial de aver\u00edas de los activos<\/strong> nunca ha sido m\u00e1s f\u00e1cil. En cuanto a los responsables de mantenimiento, la ergonom\u00eda de la herramienta facilita el acceso a los an\u00e1lisis que proporcionan datos cuantificados sobre la actividad de mantenimiento:<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-06c0169\" data-id=\"06c0169\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-372398a elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"372398a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"548\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/garantiza-y-controla-la-gestion-del-mantenimiento-de-tu-flota-de-vehiculos-y-equipos.svg\" class=\"attachment-full size-full wp-image-80245\" alt=\"Garantiza y controla la gesti\u00f3n del mantenimiento de tu flota de veh\u00edculos y equipos.\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e09450d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e09450d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-33d5ba0\" data-id=\"33d5ba0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-satellite-widget elementor-element elementor-element-cc775e7 no-margin-bottom elementor-widget elementor-widget-text-editor\" data-jet-tricks-settings='{\"satellite\":\"true\",\"satelliteType\":\"icon\",\"satellitePosition\":\"middle-left\"}' data-id=\"cc775e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-tricks-satellite jet-tricks-satellite--middle-left\"><div class=\"jet-tricks-satellite__inner\"><div class=\"jet-tricks-satellite__icon\"><div class=\"jet-tricks-satellite__icon-instance jet-tricks-icon\"><i aria-hidden=\"true\" class=\"fas fa-check\"><\/i><\/div><\/div><\/div><\/div><p>Facilitar el acceso al historial de aver\u00edas.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-658790f elementor-widget elementor-widget-spacer\" data-id=\"658790f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-satellite-widget elementor-element elementor-element-6549d02 no-margin-bottom elementor-widget elementor-widget-text-editor\" data-jet-tricks-settings='{\"satellite\":\"true\",\"satelliteType\":\"icon\",\"satellitePosition\":\"middle-left\"}' data-id=\"6549d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-tricks-satellite jet-tricks-satellite--middle-left\"><div class=\"jet-tricks-satellite__inner\"><div class=\"jet-tricks-satellite__icon\"><div class=\"jet-tricks-satellite__icon-instance jet-tricks-icon\"><i aria-hidden=\"true\" class=\"fas fa-check\"><\/i><\/div><\/div><\/div><\/div><p>Seguimiento de la disponibilidad de las piezas de repuesto.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4a0fb elementor-widget elementor-widget-spacer\" data-id=\"8d4a0fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-satellite-widget elementor-element elementor-element-018f8e5 no-margin-bottom elementor-widget elementor-widget-text-editor\" data-jet-tricks-settings='{\"satellite\":\"true\",\"satelliteType\":\"icon\",\"satellitePosition\":\"middle-left\"}' data-id=\"018f8e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-tricks-satellite jet-tricks-satellite--middle-left\"><div class=\"jet-tricks-satellite__inner\"><div class=\"jet-tricks-satellite__icon\"><div class=\"jet-tricks-satellite__icon-instance jet-tricks-icon\"><i aria-hidden=\"true\" class=\"fas fa-check\"><\/i><\/div><\/div><\/div><\/div><p>Garantizar la disponibilidad de la flota de veh\u00edculos, equipos e infraestructuras.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97b51e4 elementor-widget elementor-widget-spacer\" data-id=\"97b51e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-satellite-widget elementor-element elementor-element-bff7bf5 no-margin-bottom elementor-widget elementor-widget-text-editor\" data-jet-tricks-settings='{\"satellite\":\"true\",\"satelliteType\":\"icon\",\"satellitePosition\":\"middle-left\"}' data-id=\"bff7bf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-tricks-satellite jet-tricks-satellite--middle-left\"><div class=\"jet-tricks-satellite__inner\"><div class=\"jet-tricks-satellite__icon\"><div class=\"jet-tricks-satellite__icon-instance jet-tricks-icon\"><i aria-hidden=\"true\" class=\"fas fa-check\"><\/i><\/div><\/div><\/div><\/div><p>Permitir a los gestores acceder a los datos num\u00e9ricos.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-93dc351\" data-id=\"93dc351\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-satellite-widget elementor-element elementor-element-78304d0 no-margin-bottom elementor-widget elementor-widget-text-editor\" data-jet-tricks-settings='{\"satellite\":\"true\",\"satelliteType\":\"icon\",\"satellitePosition\":\"middle-left\"}' data-id=\"78304d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-tricks-satellite jet-tricks-satellite--middle-left\"><div class=\"jet-tricks-satellite__inner\"><div class=\"jet-tricks-satellite__icon\"><div class=\"jet-tricks-satellite__icon-instance jet-tricks-icon\"><i aria-hidden=\"true\" class=\"fas fa-check\"><\/i><\/div><\/div><\/div><\/div><p>Evitar los cuellos de botella en la producci\u00f3n y controlar el ciclo de vida de tus activos.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48453b9 elementor-widget elementor-widget-spacer\" data-id=\"48453b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-satellite-widget elementor-element elementor-element-4fb87af no-margin-bottom elementor-widget elementor-widget-text-editor\" data-jet-tricks-settings='{\"satellite\":\"true\",\"satelliteType\":\"icon\",\"satellitePosition\":\"middle-left\"}' data-id=\"4fb87af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-tricks-satellite jet-tricks-satellite--middle-left\"><div class=\"jet-tricks-satellite__inner\"><div class=\"jet-tricks-satellite__icon\"><div class=\"jet-tricks-satellite__icon-instance jet-tricks-icon\"><i aria-hidden=\"true\" class=\"fas fa-check\"><\/i><\/div><\/div><\/div><\/div><p>Mejorar la seguridad de tu flota.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e3540c elementor-widget elementor-widget-spacer\" data-id=\"3e3540c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-satellite-widget elementor-element elementor-element-6a7e420 no-margin-bottom elementor-widget elementor-widget-text-editor\" data-jet-tricks-settings='{\"satellite\":\"true\",\"satelliteType\":\"icon\",\"satellitePosition\":\"middle-left\"}' data-id=\"6a7e420\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-tricks-satellite jet-tricks-satellite--middle-left\"><div class=\"jet-tricks-satellite__inner\"><div class=\"jet-tricks-satellite__icon\"><div class=\"jet-tricks-satellite__icon-instance jet-tricks-icon\"><i aria-hidden=\"true\" class=\"fas fa-check\"><\/i><\/div><\/div><\/div><\/div><p>Gestionar el mantenimiento de cada veh\u00edculo, m\u00e1quina y equipo.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e5f62f elementor-widget elementor-widget-spacer\" data-id=\"8e5f62f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-satellite-widget elementor-element elementor-element-23ce99c no-margin-bottom elementor-widget elementor-widget-text-editor\" data-jet-tricks-settings='{\"satellite\":\"true\",\"satelliteType\":\"icon\",\"satellitePosition\":\"middle-left\"}' data-id=\"23ce99c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-tricks-satellite jet-tricks-satellite--middle-left\"><div class=\"jet-tricks-satellite__inner\"><div class=\"jet-tricks-satellite__icon\"><div class=\"jet-tricks-satellite__icon-instance jet-tricks-icon\"><i aria-hidden=\"true\" class=\"fas fa-check\"><\/i><\/div><\/div><\/div><\/div><p>Compartir algunos repositorios de datos entre diferentes departamentos de tu empresa.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7897a6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7897a6c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5b3b28\" data-id=\"f5b3b28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2022082 uael-dual-heading-align-center elementor-widget elementor-widget-uael-dual-color-heading\" data-id=\"2022082\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-module-content uael-dual-color-heading uael-heading-stack-none\">\n\t\t\t<h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-before-heading\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-first-text\" data-elementor-setting-key=\"before_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">Obt\u00e9n visibilidad de los costos de mantenimiento<\/span><\/span><span class=\"uael-adv-heading-stack\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-highlight-text\" data-elementor-setting-key=\"second_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">de tu flota de veh\u00edculos<\/span><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t<\/div>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-666df9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"666df9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f227c7c\" data-id=\"f227c7c\" data-element_type=\"column\" data-e-type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7181b2a elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"7181b2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"703\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/obten-visibilidad-de-los-costos-de-mantenimiento-de-tu-flota-de-vehiculos.svg\" class=\"attachment-full size-full wp-image-67770\" alt=\"Obte\u0301n visibilidad de los costos de mantenimiento de tu flota de vehi\u0301culos\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cb3ad5 elementor-widget elementor-widget-text-editor\" data-id=\"5cb3ad5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Un mejor seguimiento y <strong>comprensi\u00f3n de los costos de mantenimiento de tu flota <\/strong>te permitir\u00e1 adoptar las mejores pr\u00e1cticas para <strong>reducir gastos de explotaci\u00f3n<\/strong>. Hay muchos factores que influyen en los costos de mantenimiento, como los costos de las <strong>piezas de recambio, los costos de mano de obra y las condiciones de funcionamiento de los veh\u00edculos<\/strong>. Cuando los veh\u00edculos y equipos de tu flota funcionan de forma eficiente, consumen menos combustible y su ciclo de vida se alarga, mejora y optimiza.<\/p>\n<p><a href=\"\/latam\/guias\/que-es-cmms\/\">Un buen software CMMS<\/a> es esencial para tener <strong>visibilidad completa de los costos de mantenimiento<\/strong> y mantenerlos lo m\u00e1s bajos posible:<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-60f2eb3\" data-id=\"60f2eb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5667f5f elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"5667f5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"703\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/obten-visibilidad-de-los-costos-de-mantenimiento-de-tu-flota-de-vehiculos.svg\" class=\"attachment-full size-full wp-image-67770\" alt=\"Obte\u0301n visibilidad de los costos de mantenimiento de tu flota de vehi\u0301culos\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed35bf7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed35bf7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1270f76\" data-id=\"1270f76\" data-element_type=\"column\" data-e-type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c919102 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c919102\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2a0899f\" data-id=\"2a0899f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b976cea cancelnotlastchild elementor-widget elementor-widget-image\" data-id=\"b976cea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"96\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/organizar-y-visualizar-tu-flota-de-mantenimiento-de-forma-facil-e-intuitiva.svg\" class=\"attachment-full size-full wp-image-67775\" alt=\"Organizar y visualizar tu flota de mantenimiento de forma fa\u0301cil e intuitiva\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66a5cc0 no-margin elementor-widget elementor-widget-text-editor\" data-id=\"66a5cc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><strong>Organizar y visualizar<\/strong> tu flota de mantenimiento de forma f\u00e1cil e intuitiva.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3d83230\" data-id=\"3d83230\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1c7273 cancelnotlastchild elementor-widget elementor-widget-image\" data-id=\"d1c7273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"96\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/controlar-el-consumo-de-los-vehiculos-combustible-neumaticos-etc-y-gestionar-los-repuestos.svg\" class=\"attachment-full size-full wp-image-67778\" alt=\"Controlar el consumo de los vehi\u0301culos (combustible, neuma\u0301ticos, etc.) y gestionar los repuestos\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d88cb44 no-margin elementor-widget elementor-widget-text-editor\" data-id=\"d88cb44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><strong>Controlar el consumo de los veh\u00edculos<\/strong> (combustible, neum\u00e1ticos, etc.) y gestionar los repuestos.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c40d2d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c40d2d9\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4f0e076\" data-id=\"4f0e076\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3492973 cancelnotlastchild elementor-widget elementor-widget-image\" data-id=\"3492973\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"96\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/establecer-y-seguir-un-calendario-y-normas-de-mantenimiento-preventivo.svg\" class=\"attachment-full size-full wp-image-67776\" alt=\"Establecer y seguir un calendario y normas de mantenimiento preventivo\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6eef31 no-margin elementor-widget elementor-widget-text-editor\" data-id=\"e6eef31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><strong>Establecer y seguir un calendario<\/strong> y normas de <a href=\"\/latam\/blog\/plan-de-mantenimiento-preventivo-5-pasos-clave\/\">mantenimiento preventivo<\/a>.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a0dff39\" data-id=\"a0dff39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a02cf2 cancelnotlastchild elementor-widget elementor-widget-image\" data-id=\"4a02cf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"96\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/asegurar-la-total-trazabilidad-de-las-operaciones-de-mantenimiento.svg\" class=\"attachment-full size-full wp-image-67779\" alt=\"Asegurar la total trazabilidad de las operaciones de mantenimiento\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57638d7 no-margin elementor-widget elementor-widget-text-editor\" data-id=\"57638d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><strong>Asegurar la total trazabilidad<\/strong> de las operaciones de mantenimiento.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12801df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12801df\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ad31eed\" data-id=\"ad31eed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98c0ed3 cancelnotlastchild elementor-widget elementor-widget-image\" data-id=\"98c0ed3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"96\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/mejorar-la-comunicacion-entre-todas-las-partes-incluyendo-conductores-tecnicos-supervisores-etc.svg\" class=\"attachment-full size-full wp-image-67777\" alt=\"Mejorar la comunicacio\u0301n entre todas las partes, incluyendo conductores, te\u0301cnicos, supervisores, etc.\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0226b65 no-margin elementor-widget elementor-widget-text-editor\" data-id=\"0226b65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><strong>Mejorar la comunicaci\u00f3n<\/strong> entre todas las partes, incluyendo conductores, t\u00e9cnicos, supervisores, etc.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b06997\" data-id=\"3b06997\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40a2bf3 cancelnotlastchild elementor-widget elementor-widget-image\" data-id=\"40a2bf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"96\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/mejorar-el-proceso-de-toma-de-decisiones-para-la-renovacion-de-vehiculos-equipos.svg\" class=\"attachment-full size-full wp-image-67780\" alt=\"Mejorar el proceso de toma de decisiones para la renovacio\u0301n de vehi\u0301culos, equipos.\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-601c6b0 no-margin elementor-widget elementor-widget-text-editor\" data-id=\"601c6b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><strong>Mejorar el proceso de toma de decisiones<\/strong> para la renovaci\u00f3n de veh\u00edculos, equipos.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fef534 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fef534\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32c5f0e\" data-id=\"32c5f0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7d816b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d816b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-badfb46\" data-id=\"badfb46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8b844c elementor-widget elementor-widget-heading\" data-id=\"c8b844c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Integra tu CMMS a tu sistema de informaci\u00f3n<\/h2>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-607c452 elementor-widget elementor-widget-text-editor\" data-id=\"607c452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><strong>\u00a1Recopila, explota y comparte datos f\u00e1cilmente!<\/strong><\/p>\n<p>Con DimoMaint, aborda con serenidad la integraci\u00f3n de tu CMMS con las soluciones ya existentes.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-336a00f elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"336a00f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/latam\/conectores\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">M\u00e1s informaci\u00f3n <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ff4484\" data-id=\"5ff4484\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6f06f5 elementor-widget elementor-widget-image\" data-id=\"b6f06f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"498\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/integra-tu-sistema-de-informacion-dimo-maint.png\" class=\"attachment-full size-full wp-image-66470\" alt=\"Integra tu sistema de informacio\u0301n DimoMaint\" srcset=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/integra-tu-sistema-de-informacion-dimo-maint.png 540w, https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/integra-tu-sistema-de-informacion-dimo-maint-360x332.png 360w\" sizes=\"(max-width: 540px) 100vw, 540px\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f116b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f116b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a992d4\" data-id=\"5a992d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-42fda29 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"42fda29\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a96133\" data-id=\"4a96133\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3365b1e quotes elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-widget elementor-widget-testimonial-carousel\" data-id=\"3365b1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings='{\"lazyload\":\"yes\",\"speed\":500,\"loop\":\"yes\",\"space_between\":{\"unit\":\"px\",\"size\":10,\"sizes\":[]},\"space_between_tablet\":{\"unit\":\"px\",\"size\":10,\"sizes\":[]},\"space_between_mobile\":{\"unit\":\"px\",\"size\":10,\"sizes\":[]}}' data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tEl mantenimiento y la reparaci\u00f3n tienen repercusiones econ\u00f3micas y operativas. \u201cGracias al historial mensual y anual que proporciona el CMMS, podemos revisar el plan de mantenimiento y afinar los modelos financieros de nuestros activos\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/ravinala.png\" alt=\"Ravinala\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Saif Ben Ammar, Director de mantenimiento <\/span><span class=\"elementor-testimonial__title\">Aeropuertos Ravinala<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d30f7b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d30f7b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab0aecf\" data-id=\"ab0aecf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93285ab uael-dual-heading-align-center elementor-widget elementor-widget-uael-dual-color-heading\" data-id=\"93285ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-module-content uael-dual-color-heading uael-heading-stack-none\">\n\t\t\t<h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-before-heading\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-first-text\" data-elementor-setting-key=\"before_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">DimoMaint, el CMMS para<\/span><\/span><span class=\"uael-adv-heading-stack\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-highlight-text\" data-elementor-setting-key=\"second_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">el transporte y la log\u00edstica<\/span><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t<\/div>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6f3a9af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f3a9af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3f18491\" data-id=\"3f18491\" data-element_type=\"column\" data-e-type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48c4a1e elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"48c4a1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"489\" height=\"703\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/dimo-maint-el-cmms-parael-transporte-y-la-logistica.svg\" class=\"attachment-full size-full wp-image-78454\" alt=\"DimoMaint, el CMMS parael transporte y la log\u00edstica\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9368e01 elementor-widget elementor-widget-text-editor\" data-id=\"9368e01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>La soluci\u00f3n <strong>CMMS<\/strong> <strong>DimoMaint responde a las necesidades de gesti\u00f3n del mantenimiento de las infraestructuras de transporte y log\u00edstica<\/strong>, gracias a numerosas funcionalidades:<\/p>\n<ul>\n<li><strong>Mejorar la disponibilidad<\/strong> <strong>y el ciclo de vida<\/strong> de los veh\u00edculos, maquinaria y equipos con una mejor programaci\u00f3n del mantenimiento<\/li>\n<li><strong>Recibir alertas<\/strong> sobre indicadores relevantes para tu flota (kilometraje, contadores, etc.)<\/li>\n<li><strong>Generar informes de mantenimiento<\/strong> detallados y <strong>optimizar los costos<\/strong> de tu flota<\/li>\n<li><strong>Benef\u00edciate de una GMAO accesible en cualquier lugar<\/strong>, gracias a la movilidad de Android e iOS (y a la integraci\u00f3n de fotos y c\u00f3digos QR)<\/li>\n<\/ul>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4056c70\" data-id=\"4056c70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f785e1 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"9f785e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"489\" height=\"703\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/dimo-maint-el-cmms-parael-transporte-y-la-logistica.svg\" class=\"attachment-full size-full wp-image-78454\" alt=\"DimoMaint, el CMMS parael transporte y la log\u00edstica\">\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0da6b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0da6b5\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-238e1fd\" data-id=\"238e1fd\" data-element_type=\"column\" data-e-type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-satellite-widget elementor-element elementor-element-efcff0d elementor-widget elementor-widget-heading\" data-jet-tricks-settings='{\"satellite\":\"true\",\"satelliteType\":\"image\",\"satellitePosition\":\"middle-left\"}' data-id=\"efcff0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conoce m\u00e1s sobre nuestro software de mantenimiento para el transporte y la log\u00edstica<\/h2>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8622ea9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8622ea9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/latam\/wp-content\/uploads\/ficha-gmao-infrastructura-transporte.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Estoy descargando el folleto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d504758 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d504758\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c9ef5bc\" data-id=\"c9ef5bc\" data-element_type=\"column\" data-e-type=\"column\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-satellite-widget elementor-element elementor-element-c9c98f0 elementor-widget elementor-widget-heading\" data-jet-tricks-settings='{\"satellite\":\"true\",\"satelliteType\":\"image\",\"satellitePosition\":\"middle-left\"}' data-id=\"c9c98f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-tricks-satellite jet-tricks-satellite--middle-left\"><div class=\"jet-tricks-satellite__inner\"><div class=\"jet-tricks-satellite__image\"><img decoding=\"async\" class=\"jet-tricks-satellite__image-instance\" src=\"https:\/\/www.dimomaint.com\/latam\/wp-content\/uploads\/camera.svg\" alt=\"\"><\/div><\/div><\/div><h2 class=\"elementor-heading-title elementor-size-default\">Solicita una demostraci\u00f3n personalizada<\/h2>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9df250a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9df250a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-541e90e\" data-id=\"541e90e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e22309 elementor-widget elementor-widget-text-editor\" data-id=\"1e22309\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Aprende todo sobre el CMMS DimoMaint MX y participa en una presentaci\u00f3n personalizada.<\/p>\n\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fb1e3e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3fb1e3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/latam\/reservar-demo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Reserva tu demo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e3280e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e3280e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70d9f4f\" data-id=\"70d9f4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24803af elementor-widget elementor-widget-heading\" data-id=\"24803af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ve m\u00e1s all\u00e1 en la elecci\u00f3n de tu soluci\u00f3n de GMAO. D\u00e9janos guiarte en la elecci\u00f3n de una de nuestras soluciones<\/h2>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-832ce5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"832ce5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3fcf5b3\" data-id=\"3fcf5b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-704c259 elementor-nav-menu__align-center elementor-nav-menu--dropdown-mobile elementor-nav-menu__text-align-center menu-aller-plus-loin-bleu elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"704c259\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings='{\"layout\":\"horizontal\",\"submenu_icon\":{\"value\":\"&lt;i class=\\\"fas fa-caret-down\\\" aria-hidden=\\\"true\\\"&gt;&lt;\\\/i&gt;\",\"library\":\"fa-solid\"},\"toggle\":\"burger\"}' data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-background e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-704c259\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78529\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/manufactura\/\" class=\"elementor-item menu-link\">Manufactura<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78530\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/salud\/\" class=\"elementor-item menu-link\">Salud<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78531\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/energia\/\" class=\"elementor-item menu-link\">Energ\u00eda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78532\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/edificios\/\" class=\"elementor-item menu-link\">Inmobiliaria<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78533\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/medioambiente\/\" class=\"elementor-item menu-link\">Medio ambiante<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78534\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/hosteleria-restauracion\/\" class=\"elementor-item menu-link\">Hosteler\u00eda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78535\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/minera-canteras-ingenieria-civil\/\" class=\"elementor-item menu-link\">Miner\u00eda, canter\u00eda e ingenier\u00eda civil<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78536\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/transporte-logistica\/\" class=\"elementor-item menu-link\">Transporte y log\u00edstica<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78537\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/retail\/\" class=\"elementor-item menu-link\">Retail<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78538\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/educacion\/\" class=\"elementor-item menu-link\">Educacion<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-81918\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/agroalimentario\/\" class=\"elementor-item menu-link\">Agroalimentario<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-704c259\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78529\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/manufactura\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Manufactura<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78530\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/salud\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Salud<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78531\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/energia\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Energ\u00eda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78532\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/edificios\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Inmobiliaria<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78533\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/medioambiente\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Medio ambiante<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78534\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/hosteleria-restauracion\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Hosteler\u00eda<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78535\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/minera-canteras-ingenieria-civil\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Miner\u00eda, canter\u00eda e ingenier\u00eda civil<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78536\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/transporte-logistica\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Transporte y log\u00edstica<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78537\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/retail\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Retail<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-78538\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/educacion\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Educacion<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-81918\"><a href=\"https:\/\/www.dimomaint.com\/latam\/industria\/agroalimentario\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Agroalimentario<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Para las empresas de transporte y log\u00edstica, el mantenimiento de una flota de veh\u00edculos e infraestructura es vital para la satisfacci\u00f3n de los clientes, la huella de carbono y la rentabilidad \u00f3ptima. Prueba gratis de 30 d\u00edas CMMS en el transporte y la log\u00edstica:una necesidad para el departamento de mantenimiento Gestionar el mantenimiento de una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":67739,"parent":64822,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"Software de mantenimiento para el transporte y la log\u00edstica","_seopress_titles_desc":"El CMMS DimoMaint responde a las necesidades de gesti\u00f3n de mantenimiento de veh\u00edculos, m\u00e1quinas, infraestructuras de transporte y log\u00edstica.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"inline_featured_image":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-64834","page","type-page","status-publish","has-post-thumbnail"],"acf":{"url_francaise":"https:\/\/www.gmao.com\/choix-gmao\/transport-logistique\/","url_anglaise":"https:\/\/www.dimomaint.com\/industry\/transport-logistics\/","url_espagnole":"https:\/\/www.dimomaint.com\/es\/industria\/transporte-logistica\/","url_allemande":"https:\/\/www.dimomaint.de\/cmms-auswahl\/transport-logistik\/"},"_links":{"self":[{"href":"https:\/\/www.dimomaint.com\/latam\/wp-json\/wp\/v2\/pages\/64834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dimomaint.com\/latam\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dimomaint.com\/latam\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dimomaint.com\/latam\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dimomaint.com\/latam\/wp-json\/wp\/v2\/comments?post=64834"}],"version-history":[{"count":0,"href":"https:\/\/www.dimomaint.com\/latam\/wp-json\/wp\/v2\/pages\/64834\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.dimomaint.com\/latam\/wp-json\/wp\/v2\/pages\/64822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dimomaint.com\/latam\/wp-json\/wp\/v2\/media\/67739"}],"wp:attachment":[{"href":"https:\/\/www.dimomaint.com\/latam\/wp-json\/wp\/v2\/media?parent=64834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}